{"id":63,"date":"2016-04-25T19:42:06","date_gmt":"2016-04-25T17:42:06","guid":{"rendered":"http:\/\/www.pitanga.be\/index.php\/pitanga-votre-partenaire-entre-la-belgique-et-le-bresil\/?lang=pt-br"},"modified":"2021-05-26T15:02:34","modified_gmt":"2021-05-26T13:02:34","slug":"pitanga-votre-partenaire-entre-la-belgique-et-le-bresil","status":"publish","type":"page","link":"http:\/\/www.pitanga.be\/index.php\/pitanga-votre-partenaire-entre-la-belgique-et-le-bresil\/?lang=pt-br","title":{"rendered":"Pitanga: entre a B\u00e9lgica e o Brasil"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-md-4\">\n\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-188 size-medium\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/Thais-Rodrigues-300x300.jpg\" alt=\"Tha\u00eds Rodrigues\" width=\"300\" height=\"300\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Thais-Rodrigues-300x300.jpg 300w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Thais-Rodrigues-150x150.jpg 150w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Thais-Rodrigues.jpg 358w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<\/div>\n<div class=\"col-md-8\">\n\n<h2>Tha\u00eds Rodrigues<\/h2>\n<p>Acompanho empresas belgas que projetam se instalar no mercado brasileiro: busca de parceiros brasileiros, cria\u00e7\u00e3o de filial, cria\u00e7\u00e3o de empresas, instala\u00e7\u00e3o de escrit\u00f3rio de representa\u00e7\u00e3o, cursos de portugu\u00eas, forma\u00e7\u00e3o em comunica\u00e7\u00e3o intercultural, an\u00e1lise de contratos, tradu\u00e7\u00e3o de documentos, de sites web e servi\u00e7o de int\u00e9rprete.<\/p>\n<p>Para as empresas brasileiras que buscam o mercado europeu e est\u00e3o \u00e0 procura de parceiros belgas, representantes, etc., os mesmos servi\u00e7os est\u00e3o dispon\u00edveis.<\/p>\n<\/div>\n<\/div>\n<div class=\"hrule clearfix\"><\/div>\n<div class=\"oranje\">\n<h2>Um mundo de oportunidades para empresas belgas e brasileiras.<\/h2>\n<p>\u201cO Brasil \u00e9 o pa\u00eds do futuro e assim ser\u00e1 para sempre&#8230; \u201d &#8211; \u00e9 dessa forma que se falava do Brasil at\u00e9 h\u00e1 pouco tempo.<br \/>\nHoje todos os olhares se voltam para esse pa\u00eds onde, se sabe agora, o futuro finalmente se tornou presente.<\/p>\n<p>Membro do \u00ab\u00a0BRICS\u00a0\u00bb, junto com a R\u00fassia, a \u00cdndia, a China e a Africa do Sul, o Brasil \u00e9 um pa\u00eds em pleno crescimento econ\u00f4mico.<\/p>\n<p>A economia brasileira j\u00e1 ultrapassou a da Inglaterra e se classifica hoje como a sexta do mundo.<br \/>\nO Brasil \u00e9 rico em mat\u00e9rias primas e disp\u00f5e, entre outras coisas, de recursos de petr\u00f3leo e de combust\u00edveis ditos \u201cdo futuro\u201d, tais como o \u00e1lcool e outros bio-combust\u00edveis.<\/p>\n<p>Em 2007, enormes reservas de petr\u00f3leo e de g\u00e1s foram descobertas, entre o litoral do Estado de Santa Catarina at\u00e9 o litoral de Estado do Esp\u00edrito Santo, com uma extens\u00e3o total de 800 Km.<\/p>\n<p>Um estudo em andamento mostra a possibilidade de que esta plataforma chamada de pr\u00e9-sal v\u00e1 at\u00e9 o Estado do Cear\u00e1, o que colocaria o Brasil numa posi\u00e7\u00e3o extraordinariamente privilegiada.<\/p>\n<p>O Brasil \u00e9 o 5\u00b0 maior pa\u00eds do mundo, com uma popula\u00e7\u00e3o de 170 milh\u00f5es de habitantes e uma grande diversidade cultural.<br \/>\nOs empres\u00e1rios Belgas j\u00e1 compreenderam o importante papel que representa hoje o Brasil no mundo dos neg\u00f3cios.<br \/>\nPrimeiro parceiro econ\u00f4mico na Am\u00e9rica do Sul e 2\u00b0 mercado \u201calvo\u201d das exporta\u00e7\u00f5es belgas, \u00e0 frente do Canad\u00e1 e atr\u00e1s apenas dos Estado Unidos, o Brasil \u00e9 tamb\u00e9m o primeiro investidor latino-americano na B\u00e9lgica.<\/p>\n<p>Quando se sabe que entre a B\u00e9lgica e o Brasil, o com\u00e9rcio exterior bilateral foi multiplicado por 2 nos \u00faltimos 5 anos, se pode constatar que esta parceria adquire uma import\u00e2ncia crescente e altamente significativa!<\/p>\n<p>Argumento suplementar para acelerar a busca de parcerias belgo-brasileiras: a Copa do Mundo de futebol em 2014 e os Jogos Ol\u00edmpicos em 2016, com todo o potencial de bons neg\u00f3cios que isso significa.<\/p>\n<p>Sua empresa pretende uma expans\u00e3o? Busca encontrar um bom parceiro, s\u00f3lido e respeitado?<\/p>\n<p>Pitanga SNC\u00a0acompanha empresas belgas e brasileiras em todas a\u00e7\u00f5es e formalidades necess\u00e1rias para que seus objetivos sejam alcan\u00e7ados da maneira mais correta, melhor adaptada e no menor tempo poss\u00edvel.<\/p>\n<\/div>\n<div class=\"hrule clearfix\"><\/div>\n<div class=\"row\"> <div class=\"col-md-4\">\n<div class=\"su-quote su-quote-style-default su-quote-has-cite\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">Some situation needs some person with the right keys, overall in order to develop new projects. Regarding Brazil, Tha\u00efs is surely this person. With her connections, her serious mind and her professionalism, she can open doors that you&rsquo;ve never heard.<span class=\"su-quote-cite\"><a href=\"https:\/\/www.linkedin.com\/in\/thaisrodriguesbrasil\/fr\" target=\"_blank\">David Welner sur LinkedIn<\/a><\/span><\/div><\/div>\n<\/div><div class=\"col-md-4\">\n<div class=\"su-quote su-quote-style-default su-quote-has-cite\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">Thais is a very dedicated, professional person, she is very pragmatical in her teaching approach. If you want to learn Portuguese from A to Z (language, culture, best practices,) I can strongly recommend you her. She is inspiring.<span class=\"su-quote-cite\"><a href=\"https:\/\/www.linkedin.com\/in\/thaisrodriguesbrasil\/fr\" target=\"_blank\">Khady Gaye sur LinkedIn<\/a><\/span><\/div><\/div>\n<\/div><\/div>\n<div class=\"hrule clearfix\"><\/div>\n<div class=\"row\"> <div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-144\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/Puratos.png\" alt=\"Puratos\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Puratos.png 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Puratos-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-156\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/scania-group-e1461935179645.jpg\" alt=\"scania-group\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/scania-group-e1461935179645.jpg 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/scania-group-e1461935179645-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-146\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/Sarens.png\" alt=\"Sarens\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Sarens.png 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Sarens-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-159 size-full\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/agilys-logo-e1461935653148.jpg\" alt=\"agilys-logo\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/agilys-logo-e1461935653148.jpg 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/agilys-logo-e1461935653148-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><\/div>\n<p>&nbsp;<\/p>\n<div class=\"row\"> <div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-165\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/Logo-omya-e1461936134462.jpg\" alt=\"Logo-omya\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Logo-omya-e1461936134462.jpg 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Logo-omya-e1461936134462-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-162\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/Lhoist-logo.png\" alt=\"Lhoist-logo\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Lhoist-logo.png 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/Lhoist-logo-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-168\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/medialaan.png\" alt=\"medialaan\" width=\"200\" height=\"200\" srcset=\"http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/medialaan.png 200w, http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/medialaan-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<\/div><div class=\"col-md-3\">\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-171\" src=\"http:\/\/www.pitanga.be\/wp-content\/uploads\/2016\/04\/detail_silly-300x225.png\" alt=\"Brasserie de Silly\" width=\"300\" height=\"225\" \/><\/p>\n<\/div><\/div>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-2'  data-version='5.12.70'><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>A lire aussi<\/h3><\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"http:\/\/www.pitanga.be\/index.php\/2016\/03\/18\/cidade-maravilhosa-caminhe-pelo-centro-e-pelas-praias-do-rio-de-janeiro\/\" class=\"image-list\"  >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/04\/mirante-do-leblon-rio-de-janeiro-150x150.jpeg') 50% 50% no-repeat;width: 130px;height:90px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"http:\/\/www.pitanga.be\/index.php\/2016\/03\/18\/cidade-maravilhosa-caminhe-pelo-centro-e-pelas-praias-do-rio-de-janeiro\/\" style=\"font-size:16px;font-weight:bold;;line-height:24px;\"> Cidade Maravilhosa: caminhe pelo Centro e pelas praias do Rio de Janeiro  <\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:12px;\" ><\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/14\/o-nosso-lindo-brasil-um-passeio-em-alta-definicao\/\" class=\"image-list\"  >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/05\/O-Nosso-Lindo-Brasil-150x150.png') 50% 50% no-repeat;width: 130px;height:90px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/14\/o-nosso-lindo-brasil-um-passeio-em-alta-definicao\/\" style=\"font-size:16px;font-weight:bold;;line-height:24px;\"> O Nosso Lindo Brasil: Um Passeio em Alta Defini\u00e7\u00e3o!  <\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:12px;\" >Pequena viagem virtual ao Brasil...\r\nAproveitem para sonhar!!!\r\n\r\n<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/16\/candido-portinari-peintre-bresilien\/\" class=\"image-list\"  >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/05\/Candida-Portinaro-flautista-150x150.jpg') 50% 50% no-repeat;width: 130px;height:90px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/16\/candido-portinari-peintre-bresilien\/\" style=\"font-size:16px;font-weight:bold;;line-height:24px;\"> C\u00e2ndido Portinari \u2013 peintre br\u00e9silien  <\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:12px;\" >Arte brasileira\r\nRevendo... porque sempre vale a pena!\r\n\r\nC\u00e2ndido Portinari - pintor brasileiro, nascido em Brodowski, no Estado de S\u00e3o Paulo, em 29 de dezembro de 1903 e morto no Rio de Janeiro, em 6...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/11\/gabriel-grossi-bebe-kramer-e-felix-junior-no-programa-casa-do-som\/\" class=\"image-list\"  >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/05\/Gabriel-Grossi-Bebe-Kramer-e-Felix-Ju\u0301nior-150x150.png') 50% 50% no-repeat;width: 130px;height:90px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"http:\/\/www.pitanga.be\/index.php\/2016\/05\/11\/gabriel-grossi-bebe-kramer-e-felix-junior-no-programa-casa-do-som\/\" style=\"font-size:16px;font-weight:bold;;line-height:24px;\"> Gabriel Grossi, Bebe Kramer e Felix Junior no Programa Casa do Som  <\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:12px;\" >Queridos amigos do \"Cours de Portugais du Br\u00e9sil\", mil desculpas pela loooonga aus\u00eancia!\r\n\u00c0s vezes as tais \"24 horas\" s\u00e3o t\u00e3o curtas para tantos compromissos que estes acabam se extrapolando em muuuit...<\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"relatedthumb yuzo-list  \" style=\"\"  >  \n\t\t\t\t\t\t  <a  href=\"http:\/\/www.pitanga.be\/index.php\/2016\/07\/24\/pe-na-areia-pra-curtir-o-verao\/\" class=\"image-list\"  >\n\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t <div class=\"yuzo-img\" style=\"background:url('http:\/\/www.pitanga.be\/pta\/wp-content\/uploads\/2016\/07\/pe-na-areia-diogo-nogueira-150x150.png') 50% 50% no-repeat;width: 130px;height:90px;margin-bottom: 5px;background-size:  cover;  \"><\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <\/a>\n\t\t\t\t\t\t  <a  class=\"link-list yuzo__text--title\" href=\"http:\/\/www.pitanga.be\/index.php\/2016\/07\/24\/pe-na-areia-pra-curtir-o-verao\/\" style=\"font-size:16px;font-weight:bold;;line-height:24px;\"> \u00ab\u00a0P\u00e9 na Areia\u00a0\u00bb, pra curtir o ver\u00e3o!  <\/a>\n\t\t\t\t\t\t\t\t<span class=\"yuzo_text\" style=\"font-size:12px;\" ><\/span>\n\t\t\t\t\t\t   \n\t\t\t\t\t\t<\/div>\n<\/div> <style>\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb { background: !important; -webkit-transition: background 0.2s linear; -moz-transition: background 0.2s linear; -o-transition: background 0.2s linear; transition: background 0.2s linear;;color:!important; }\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb:hover{background:#ffffff !important;color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .yuzo_text {color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb:hover .yuzo_text {color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb a{color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb a:hover{color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb:hover a{ color:!important;}\n\t\t\t\t\t\t.yuzo_related_post .relatedthumb{  margin: 2px  0px  2px  0px;   padding: 8px  5px  8px  5px;  }\n\t\t\t\t\t\t\n\t\t\t\t\t\t<\/style>  <!-- End Yuzo :) --><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Um mundo de oportunidades para empresas belgas e brasileiras. \u201cO Brasil \u00e9 o pa\u00eds do futuro e assim ser\u00e1 para sempre&#8230; \u201d &#8211; \u00e9 dessa forma que se falava do Brasil at\u00e9 h\u00e1 pouco tempo. Hoje todos os olhares se &hellip; <a href=\"http:\/\/www.pitanga.be\/index.php\/pitanga-votre-partenaire-entre-la-belgique-et-le-bresil\/?lang=pt-br\">Lire la suite\u00ad\u00ad<\/a><!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":54,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-feature.php","meta":{"kt_blocks_editor_width":""},"_links":{"self":[{"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/pages\/63"}],"collection":[{"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":9,"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/pages\/63\/revisions"}],"predecessor-version":[{"id":640,"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/pages\/63\/revisions\/640"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/media\/54"}],"wp:attachment":[{"href":"http:\/\/www.pitanga.be\/index.php\/wp-json\/wp\/v2\/media?parent=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}